{"id":61776,"date":"2024-04-26T23:35:03","date_gmt":"2024-04-27T04:35:03","guid":{"rendered":"https:\/\/www.lotsdesurplus.com\/?post_type=product&#038;p=61776"},"modified":"2024-08-01T20:19:49","modified_gmt":"2024-08-02T01:19:49","slug":"20-conteneurs-sofas-sectionnels-et-meubles-de-patio-chaises-interieures-etc","status":"publish","type":"product","link":"https:\/\/www.lotsdesurplus.com\/en\/product\/20-conteneurs-sofas-sectionnels-et-meubles-de-patio-chaises-interieures-etc\/","title":{"rendered":"20 Conteneurs Sofas Sectionnels et Meubles de Patio, Chaises Int\u00e9rieures, etc"},"content":{"rendered":"<p>20 Conteneurs Sofas Sectionnels et<\/p>\n<p>Meubles de Patio, Chaises Int\u00e9rieures, etc<\/p>\n<p>Beaucoup de Mod\u00e8les et Couleurs<\/p>\n<p><span style=\"font-size: 14pt; color: #ff0000;\">VENTE MINIMUM DE 10,000$ AVEC POSSIBILIT\u00c9 DE COMBINER<\/span><\/p>\n<p><span style=\"font-size: 14pt; color: #ff0000;\">D`AUTRES LOTS DE MEUBLES DE L`ENTREP\u00d4T 027 DU SITE WEB LOTSDESURPLUS COM<\/span><\/p>\n<p>INFOS: ventes@lotsdesurplus.com<\/p>\n","protected":false},"excerpt":{"rendered":"<p>20 Conteneurs Sofas Sectionnels et<\/p>\n<p>Meubles de Patio, Chaises Int\u00e9rieures, etc<\/p>\n<p>Beaucoup de Mod\u00e8les et Couleurs<\/p>\n<p><span style=\"font-size: 14pt; color: #ff0000;\">VENTE MINIMUM DE 10,000$ AVEC POSSIBILIT\u00c9 DE COMBINER<\/span><\/p>\n<p><span style=\"font-size: 14pt; color: #ff0000;\">D`AUTRES LOTS DE MEUBLES DE L`ENTREP\u00d4T 027 DU SITE WEB LOTSDESURPLUS COM<\/span><\/p>\n<p>INFOS: ventes@lotsdesurplus.com<\/p>\n","protected":false},"featured_media":61777,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_ria_meta_titre":"","_ria_meta_description":"","_ria_resume_generation":""},"product_brand":[],"product_cat":[40,144,108,303,48,43,15],"product_tag":[258],"class_list":{"0":"post-61776","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-lots-en-vedette-ou-en-promotion","7":"product_cat-camion-complet","8":"product_cat-entrepot-complet-a-vendre","9":"product_cat-flips-rapides-en-tres-gros","10":"product_cat-lots-de-palettes","11":"product_cat-meubles","12":"product_cat-marchandises-en-lot-autre","13":"product_tag-entrepot-027","15":"first","16":"instock","17":"featured","18":"shipping-taxable","19":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>20 Conteneurs Sofas Sectionnels et Meubles de Patio, Chaises Int\u00e9rieures, etc - Lots de surplus<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.lotsdesurplus.com\/en\/product\/20-conteneurs-sofas-sectionnels-et-meubles-de-patio-chaises-interieures-etc\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"20 Conteneurs Sofas Sectionnels et Meubles de Patio, Chaises Int\u00e9rieures, etc - Lots de surplus\" \/>\n<meta property=\"og:description\" content=\"20 Conteneurs Sofas Sectionnels et  Meubles de Patio, Chaises Int\u00e9rieures, etc  Beaucoup de Mod\u00e8les et Couleurs  VENTE MINIMUM DE 10,000$ AVEC POSSIBILIT\u00c9 DE COMBINER  D`AUTRES LOTS DE MEUBLES DE L`ENTREP\u00d4T 027 DU SITE WEB LOTSDESURPLUS COM  INFOS: ventes@lotsdesurplus.com\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.lotsdesurplus.com\/en\/product\/20-conteneurs-sofas-sectionnels-et-meubles-de-patio-chaises-interieures-etc\/\" \/>\n<meta property=\"og:site_name\" content=\"Lots de surplus\" \/>\n<meta property=\"article:modified_time\" content=\"2024-08-02T01:19:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.lotsdesurplus.com\/wp-content\/uploads\/2024\/04\/meubles.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"750\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.lotsdesurplus.com\/en\/product\/20-conteneurs-sofas-sectionnels-et-meubles-de-patio-chaises-interieures-etc\/\",\"url\":\"https:\/\/www.lotsdesurplus.com\/en\/product\/20-conteneurs-sofas-sectionnels-et-meubles-de-patio-chaises-interieures-etc\/\",\"name\":\"20 Conteneurs Sofas Sectionnels et Meubles de Patio, Chaises Int\u00e9rieures, etc - Lots de surplus\",\"isPartOf\":{\"@id\":\"https:\/\/www.lotsdesurplus.com\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.lotsdesurplus.com\/en\/product\/20-conteneurs-sofas-sectionnels-et-meubles-de-patio-chaises-interieures-etc\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.lotsdesurplus.com\/en\/product\/20-conteneurs-sofas-sectionnels-et-meubles-de-patio-chaises-interieures-etc\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.lotsdesurplus.com\/wp-content\/uploads\/2024\/04\/meubles.jpg\",\"datePublished\":\"2024-04-27T04:35:03+00:00\",\"dateModified\":\"2024-08-02T01:19:49+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.lotsdesurplus.com\/en\/product\/20-conteneurs-sofas-sectionnels-et-meubles-de-patio-chaises-interieures-etc\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.lotsdesurplus.com\/en\/product\/20-conteneurs-sofas-sectionnels-et-meubles-de-patio-chaises-interieures-etc\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.lotsdesurplus.com\/en\/product\/20-conteneurs-sofas-sectionnels-et-meubles-de-patio-chaises-interieures-etc\/#primaryimage\",\"url\":\"https:\/\/www.lotsdesurplus.com\/wp-content\/uploads\/2024\/04\/meubles.jpg\",\"contentUrl\":\"https:\/\/www.lotsdesurplus.com\/wp-content\/uploads\/2024\/04\/meubles.jpg\",\"width\":1000,\"height\":750,\"caption\":\"meubles 200 CONTENEURS Sofas Sectionnels et Meubles de Patio, Chaises Int\u00e9rieures, etc\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.lotsdesurplus.com\/en\/product\/20-conteneurs-sofas-sectionnels-et-meubles-de-patio-chaises-interieures-etc\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.lotsdesurplus.com\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\/\/www.lotsdesurplus.com\/en\/shop\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Promotional Lots\",\"item\":\"https:\/\/www.lotsdesurplus.com\/en\/product_category\/promotional-lots\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"20 Conteneurs Sofas Sectionnels et Meubles de Patio, Chaises Int\u00e9rieures, etc\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.lotsdesurplus.com\/en\/#website\",\"url\":\"https:\/\/www.lotsdesurplus.com\/en\/\",\"name\":\"Lots de surplus\",\"description\":\"Au prix du gros\",\"publisher\":{\"@id\":\"https:\/\/www.lotsdesurplus.com\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.lotsdesurplus.com\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.lotsdesurplus.com\/en\/#organization\",\"name\":\"Lots de surplus\",\"url\":\"https:\/\/www.lotsdesurplus.com\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.lotsdesurplus.com\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.lotsdesurplus.com\/wp-content\/uploads\/2025\/08\/logo-lot-de-surplus.png\",\"contentUrl\":\"https:\/\/www.lotsdesurplus.com\/wp-content\/uploads\/2025\/08\/logo-lot-de-surplus.png\",\"width\":600,\"height\":181,\"caption\":\"Lots de surplus\"},\"image\":{\"@id\":\"https:\/\/www.lotsdesurplus.com\/en\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"20 Conteneurs Sofas Sectionnels et Meubles de Patio, Chaises Int\u00e9rieures, etc - Lots de surplus","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.lotsdesurplus.com\/en\/product\/20-conteneurs-sofas-sectionnels-et-meubles-de-patio-chaises-interieures-etc\/","og_locale":"en_US","og_type":"article","og_title":"20 Conteneurs Sofas Sectionnels et Meubles de Patio, Chaises Int\u00e9rieures, etc - Lots de surplus","og_description":"20 Conteneurs Sofas Sectionnels et  Meubles de Patio, Chaises Int\u00e9rieures, etc  Beaucoup de Mod\u00e8les et Couleurs  VENTE MINIMUM DE 10,000$ AVEC POSSIBILIT\u00c9 DE COMBINER  D`AUTRES LOTS DE MEUBLES DE L`ENTREP\u00d4T 027 DU SITE WEB LOTSDESURPLUS COM  INFOS: ventes@lotsdesurplus.com","og_url":"https:\/\/www.lotsdesurplus.com\/en\/product\/20-conteneurs-sofas-sectionnels-et-meubles-de-patio-chaises-interieures-etc\/","og_site_name":"Lots de surplus","article_modified_time":"2024-08-02T01:19:49+00:00","og_image":[{"width":1000,"height":750,"url":"https:\/\/www.lotsdesurplus.com\/wp-content\/uploads\/2024\/04\/meubles.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.lotsdesurplus.com\/en\/product\/20-conteneurs-sofas-sectionnels-et-meubles-de-patio-chaises-interieures-etc\/","url":"https:\/\/www.lotsdesurplus.com\/en\/product\/20-conteneurs-sofas-sectionnels-et-meubles-de-patio-chaises-interieures-etc\/","name":"20 Conteneurs Sofas Sectionnels et Meubles de Patio, Chaises Int\u00e9rieures, etc - Lots de surplus","isPartOf":{"@id":"https:\/\/www.lotsdesurplus.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.lotsdesurplus.com\/en\/product\/20-conteneurs-sofas-sectionnels-et-meubles-de-patio-chaises-interieures-etc\/#primaryimage"},"image":{"@id":"https:\/\/www.lotsdesurplus.com\/en\/product\/20-conteneurs-sofas-sectionnels-et-meubles-de-patio-chaises-interieures-etc\/#primaryimage"},"thumbnailUrl":"https:\/\/www.lotsdesurplus.com\/wp-content\/uploads\/2024\/04\/meubles.jpg","datePublished":"2024-04-27T04:35:03+00:00","dateModified":"2024-08-02T01:19:49+00:00","breadcrumb":{"@id":"https:\/\/www.lotsdesurplus.com\/en\/product\/20-conteneurs-sofas-sectionnels-et-meubles-de-patio-chaises-interieures-etc\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.lotsdesurplus.com\/en\/product\/20-conteneurs-sofas-sectionnels-et-meubles-de-patio-chaises-interieures-etc\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.lotsdesurplus.com\/en\/product\/20-conteneurs-sofas-sectionnels-et-meubles-de-patio-chaises-interieures-etc\/#primaryimage","url":"https:\/\/www.lotsdesurplus.com\/wp-content\/uploads\/2024\/04\/meubles.jpg","contentUrl":"https:\/\/www.lotsdesurplus.com\/wp-content\/uploads\/2024\/04\/meubles.jpg","width":1000,"height":750,"caption":"meubles 200 CONTENEURS Sofas Sectionnels et Meubles de Patio, Chaises Int\u00e9rieures, etc"},{"@type":"BreadcrumbList","@id":"https:\/\/www.lotsdesurplus.com\/en\/product\/20-conteneurs-sofas-sectionnels-et-meubles-de-patio-chaises-interieures-etc\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.lotsdesurplus.com\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/www.lotsdesurplus.com\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"Promotional Lots","item":"https:\/\/www.lotsdesurplus.com\/en\/product_category\/promotional-lots\/"},{"@type":"ListItem","position":4,"name":"20 Conteneurs Sofas Sectionnels et Meubles de Patio, Chaises Int\u00e9rieures, etc"}]},{"@type":"WebSite","@id":"https:\/\/www.lotsdesurplus.com\/en\/#website","url":"https:\/\/www.lotsdesurplus.com\/en\/","name":"Lots de surplus","description":"Au prix du gros","publisher":{"@id":"https:\/\/www.lotsdesurplus.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.lotsdesurplus.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.lotsdesurplus.com\/en\/#organization","name":"Lots de surplus","url":"https:\/\/www.lotsdesurplus.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.lotsdesurplus.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.lotsdesurplus.com\/wp-content\/uploads\/2025\/08\/logo-lot-de-surplus.png","contentUrl":"https:\/\/www.lotsdesurplus.com\/wp-content\/uploads\/2025\/08\/logo-lot-de-surplus.png","width":600,"height":181,"caption":"Lots de surplus"},"image":{"@id":"https:\/\/www.lotsdesurplus.com\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.lotsdesurplus.com\/en\/wp-json\/wp\/v2\/product\/61776","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lotsdesurplus.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.lotsdesurplus.com\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lotsdesurplus.com\/en\/wp-json\/wp\/v2\/comments?post=61776"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lotsdesurplus.com\/en\/wp-json\/wp\/v2\/media\/61777"}],"wp:attachment":[{"href":"https:\/\/www.lotsdesurplus.com\/en\/wp-json\/wp\/v2\/media?parent=61776"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.lotsdesurplus.com\/en\/wp-json\/wp\/v2\/product_brand?post=61776"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.lotsdesurplus.com\/en\/wp-json\/wp\/v2\/product_cat?post=61776"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.lotsdesurplus.com\/en\/wp-json\/wp\/v2\/product_tag?post=61776"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}